{"id":11076,"date":"2023-04-17T15:47:32","date_gmt":"2023-04-17T13:47:32","guid":{"rendered":"https:\/\/muratorimachines.com\/?p=11076"},"modified":"2025-04-29T09:59:26","modified_gmt":"2025-04-29T07:59:26","slug":"fresare-piegare-bordo","status":"publish","type":"post","link":"https:\/\/muratorimachines.com\/it\/fresare-piegare-bordo\/","title":{"rendered":"Come fresare e piegare in continuo il bordo dei pannelli"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"11076\" class=\"elementor elementor-11076\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c62c534 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c62c534\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bc03875\" data-id=\"bc03875\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3bc7be elementor-widget elementor-widget-image\" data-id=\"e3bc7be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-loader\/\" target=\"_blank\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1536\" height=\"921\" src=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2023\/06\/lavorare-il-bordo-del-pannello-1536x921.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-11090\" alt=\"\" srcset=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2023\/06\/lavorare-il-bordo-del-pannello-1536x921.jpg 1536w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2023\/06\/lavorare-il-bordo-del-pannello-300x180.jpg 300w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2023\/06\/lavorare-il-bordo-del-pannello-1024x614.jpg 1024w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2023\/06\/lavorare-il-bordo-del-pannello-768x461.jpg 768w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2023\/06\/lavorare-il-bordo-del-pannello-2048x1228.jpg 2048w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba3a535 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba3a535\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9056cf\" data-id=\"c9056cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d09976c elementor-widget elementor-widget-heading\" data-id=\"d09976c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qual \u00e8 il modo pi\u00f9 efficace per lavorare e rendere bello il bordo dei pannelli?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3ad092 elementor-widget elementor-widget-text-editor\" data-id=\"c3ad092\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>I pannelli compositi per facciate architettoniche, per il settore dei trasporti, cos\u00ec come quelli per l&#8217;industria e il Visual Communication, devono rispondere a precisi requisiti tecnici, garantire ottime performance e resistenza agli agenti atmosferici. Ma anche l&#8217;aspetto estetico riveste un ruolo importante.<\/p><p>Gli stessi pannelli, infatti, oltre a conferire pregio agli involucri edilizi e negli interni dei trasporti, sono utilizzati nell\u2019interior design e nel visual communication, ambiti in cui l\u2019estetica \u00e8 fondamentale, se non essenza stessa del progetto. Da qui la necessit\u00e0 di <strong>rendere bello anche il bordo dei pannelli compositi<\/strong>.<\/p><p><strong>Qual \u00e8 il modo pi\u00f9 efficace per lavorare e rendere bello il bordo dei pannelli<\/strong>?<br \/>Sicuramente quello di utilizzare una tecnologia unica sul mercato per la fresatura e la piegatura del bordo in continuo, come <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-bender\/\">Alu Bender.<\/a><\/p><p>S\u00ec, per soddisfare le esigenze tecniche di durabilit\u00e0 e resistenza a fenomeni atmosferici, e coniugarle con quelle estetiche, in Muratori Machines abbiamo progettato e realizzato <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-bender\/\">Alu Bender<\/a>: macchina multifunzionale per la lavorazione del bordo dei pannelli compositi impiegati in architettura, trasporti, interior design e visual communication.<\/p><p><strong>Una tecnologia unica sul mercato, fatta per la fresatura e la piegatura automatica del bordo in continuo<\/strong><\/p><p>La prima particolarit\u00e0 di <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-bender\/\">Alu Bender<\/a> \u00e8 che \u00e8 unica sul mercato ed \u00e8 per la fresatura e la piegatura automatica del bordo in continuo.<\/p><p><strong><a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-bender\/\">Alu Bender<\/a> \u00e8 in grado di lavorare con la massima precisione:<\/strong><\/p><ul><li>doppia piega interna (double bending)<\/li><li>lavorazioni multiple su Nido d\u2019ape d\u2019alluminio<\/li><li>finitura bordo dei pannelli in Fibrocemento e HPL<\/li><li>orlatura multipla del bordo ACM, Core PE e Core Minerale<\/li><\/ul><p>\u00a0<\/p><p>I pannelli, anche di grandi dimensioni, sono lavorati e piegati in modo estremamente accurato, supportati in entrata e in uscita con un avanzamento preciso e sicuro, sia per il pannello che per l\u2019operatore.<\/p><p><strong>Ecco 4 delle ragioni per scegliere <\/strong><a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-bender\/\"><strong>Alu Bender<\/strong><\/a><strong> per la lavorazione del bordo dei pannelli compositi:<\/strong><\/p><ol><li>nei pannelli in ACM, consente l\u2019orlatura del bordo, eventualmente anche con piegatura doppia esterna<\/li><li>nei pannelli in Nido d\u2019ape in alluminio, esegue un raggio di piegatura perfetto sul bordo, nascondendo il core alla vista e migliorando la resistenza agli agenti atmosferici<\/li><li>nella fresatura dei bordi dei pannelli in HPL e fibrocemento, elimina le tallonature e consente la bisellatura degli spigoli<\/li><li>nei pannelli in fibrocemento, applica anche il liquido LUKO\u00ae, all\u2019interno dello stesso ciclo di lavorazione<\/li><li>nei pannelli in Nido d\u2019ape in alluminio, esegue automaticamente lo schiacciamento in continuo, per il montaggio accoppiato o con profilo ad \u201cH\u201d<\/li><\/ol><p>\u00a0<\/p><p>Alu Bender \u00e8 unica, ma non \u00e8 la sola <a href=\"https:\/\/muratorimachines.com\/prodotti\/\">tecnologia Muratori Machines per la lavorazione del bordo<\/a>. Tra le macchine di Edge Bending, figura infatti anche la serie <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-doubler-p\/\">Alu Doubler<\/a> che si concretizza in due macchine, <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-doubler-f\/\">Alu Doubler F<\/a> e <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-doubler-p\/\">Alu Doubler P.<\/a><\/p><p><a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-doubler-f\/\">Alu Doubler F<\/a> \u00e8 studiata per il taglio di una delle due pelli di pannelli a Nido d\u2019ape in alluminio e VGroove una o due linee per la piega singola o doppia. <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-doubler-p\/\">Alu Doubler P<\/a> \u00e8 progettata per piegare la pelle principale dei pannelli a Nido d\u2019ape in alluminio precedentemente lavorati su <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-doubler-f\/\">Alu Doubler F<\/a> o tramite <a href=\"https:\/\/muratorimachines.com\/prodotti\/alu-ranger-vgroove\/\">CNC Alu Ranger<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61960ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61960ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-581929d\" data-id=\"581929d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8ffeaf elementor-widget elementor-widget-heading\" data-id=\"f8ffeaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/muratorimachines.com\/contatti\/\">Cerchi un unico partner per la lavorazione di pannelli su Centro di Lavoro o con tecnologie di fresatura e piega?<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9b5385 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c9b5385\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/muratorimachines.com\/contatti\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contattaci<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ed7a6f elementor-widget elementor-widget-spacer\" data-id=\"4ed7a6f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf63abb elementor-widget elementor-widget-heading\" data-id=\"bf63abb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/muratorimachines.com\/contatti\/\">Potrebbe interessarti leggere anche:<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83749ac elementor-grid-2 elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-posts--thumbnail-top elementor-posts--show-avatar elementor-card-shadow-yes elementor-posts__hover-gradient elementor-widget elementor-widget-posts\" data-id=\"83749ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;cards_columns&quot;:&quot;2&quot;,&quot;cards_columns_tablet&quot;:&quot;2&quot;,&quot;cards_columns_mobile&quot;:&quot;1&quot;,&quot;cards_row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:35,&quot;sizes&quot;:[]},&quot;cards_row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;cards_row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"posts.cards\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-posts-container elementor-posts elementor-posts--skin-cards elementor-grid\" role=\"list\">\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22471 post type-post status-publish format-standard has-post-thumbnail hentry category-tecnologie tag-centro-di-lavoro-con-piano-verticale tag-acm-2 tag-camera tag-pannelli-compositi tag-materiali-compositi tag-cnc\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/muratorimachines.com\/it\/spazzola-di-pulizia-piano-su-ranger-cnc\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Table-cleaning-brush-Muratori-Machines-300x168.png\" class=\"attachment-medium size-medium wp-image-22476\" alt=\"\" srcset=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Table-cleaning-brush-Muratori-Machines-300x168.png 300w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Table-cleaning-brush-Muratori-Machines-1024x572.png 1024w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Table-cleaning-brush-Muratori-Machines-768x429.png 768w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Table-cleaning-brush-Muratori-Machines.png 1220w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Macchine e tecnologie<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/muratorimachines.com\/it\/spazzola-di-pulizia-piano-su-ranger-cnc\/\" >\n\t\t\t\tSpazzola di pulizia piano su Ranger CNC\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Trucioli e superfici delicate: come il CNC Ranger pulisce il piano durante il carico La spazzola rotante del CNC Ranger con Loader + Feeder pulisce<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/muratorimachines.com\/it\/spazzola-di-pulizia-piano-su-ranger-cnc\/\" aria-label=\"Read more about Spazzola di pulizia piano su Ranger CNC\" tabindex=\"-1\" >\n\t\t\tLeggi di pi\u00f9 \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22398 post type-post status-publish format-standard has-post-thumbnail hentry category-tecnologie tag-materiali-compositi tag-cnc tag-centro-di-lavoro-con-piano-verticale tag-acm-2 tag-camera tag-pannelli-compositi\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/muratorimachines.com\/it\/telecamera-crocini-ranger-cnc\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"170\" src=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Muratori-Machines-Camera-300x170.png\" class=\"attachment-medium size-medium wp-image-22405\" alt=\"\" srcset=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Muratori-Machines-Camera-300x170.png 300w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Muratori-Machines-Camera-1024x580.png 1024w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Muratori-Machines-Camera-768x435.png 768w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/07\/Muratori-Machines-Camera.png 1352w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Macchine e tecnologie<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/muratorimachines.com\/it\/telecamera-crocini-ranger-cnc\/\" >\n\t\t\t\tTelecamera per crocini di registro su Ranger CNC\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Nel sign making, nell&#8217;arredamento e nell&#8217;interior design, capita ogni giorno: un pannello pre-stampato \u2014 un adesivo, una targa, un pannello grafico \u2014 deve essere tagliato<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/muratorimachines.com\/it\/telecamera-crocini-ranger-cnc\/\" aria-label=\"Read more about Telecamera per crocini di registro su Ranger CNC\" tabindex=\"-1\" >\n\t\t\tLeggi di pi\u00f9 \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22249 post type-post status-publish format-standard has-post-thumbnail hentry category-tecnologie category-fiere-ed-eventi tag-pannelli-compositi tag-lavorazione-bordo tag-acm-2 tag-alu-bender-2\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/muratorimachines.com\/it\/doppia-fresatura-e-doppia-piegatura\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"167\" src=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/04\/Doppia-fresatura-e-doppia-piegatura_Alu-Bender-300x167.png\" class=\"attachment-medium size-medium wp-image-22258\" alt=\"\" srcset=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/04\/Doppia-fresatura-e-doppia-piegatura_Alu-Bender-300x167.png 300w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/04\/Doppia-fresatura-e-doppia-piegatura_Alu-Bender-1024x571.png 1024w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/04\/Doppia-fresatura-e-doppia-piegatura_Alu-Bender-768x428.png 768w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/04\/Doppia-fresatura-e-doppia-piegatura_Alu-Bender-1536x856.png 1536w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/04\/Doppia-fresatura-e-doppia-piegatura_Alu-Bender-2048x1141.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Macchine e tecnologie<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/muratorimachines.com\/it\/doppia-fresatura-e-doppia-piegatura\/\" >\n\t\t\t\tDoppia fresatura e doppia piegatura | Alu Bender\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Nel mondo della lavorazione dei pannelli compositi, alcune richieste cliente rappresentano vere sfide produttive. \u00c8 il caso della doppia piega su pannelli in alluminio honeycomb,<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/muratorimachines.com\/it\/doppia-fresatura-e-doppia-piegatura\/\" aria-label=\"Read more about Doppia fresatura e doppia piegatura | Alu Bender\" tabindex=\"-1\" >\n\t\t\tLeggi di pi\u00f9 \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<article class=\"elementor-post elementor-grid-item post-22153 post type-post status-publish format-standard has-post-thumbnail hentry category-tecnologie category-fiere-ed-eventi tag-pannelli-compositi tag-lavorazione-bordo tag-centro-di-lavoro-con-piano-verticale tag-acm-2 tag-ligna-2025 tag-sign-making tag-signage\" role=\"listitem\">\n\t\t\t<div class=\"elementor-post__card\">\n\t\t\t\t<a class=\"elementor-post__thumbnail__link\" href=\"https:\/\/muratorimachines.com\/it\/isa-2026\/\" tabindex=\"-1\" ><div class=\"elementor-post__thumbnail\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"169\" src=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/03\/Banner-sito-Muratori-Machines-300x169.png\" class=\"attachment-medium size-medium wp-image-22168\" alt=\"\" srcset=\"https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/03\/Banner-sito-Muratori-Machines-300x169.png 300w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/03\/Banner-sito-Muratori-Machines-1024x576.png 1024w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/03\/Banner-sito-Muratori-Machines-768x432.png 768w, https:\/\/muratorimachines.com\/wp-content\/uploads\/2026\/03\/Banner-sito-Muratori-Machines.png 1366w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/div><\/a>\n\t\t\t\t<div class=\"elementor-post__badge\">Macchine e tecnologie<\/div>\n\t\t\t\t<div class=\"elementor-post__avatar\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-post__text\">\n\t\t\t\t<h3 class=\"elementor-post__title\">\n\t\t\t<a href=\"https:\/\/muratorimachines.com\/it\/isa-2026\/\" >\n\t\t\t\tMuratori Machines a ISA Expo 2026: Automazione CNC Verticale per il Sign Making\t\t\t<\/a>\n\t\t<\/h3>\n\t\t\t\t<div class=\"elementor-post__excerpt\">\n\t\t\t<p>Quest&#8217;anno, abbiamo deciso di partecipare a ISA International Sign Expo 2026 a Orlando (FL), per presentare Ranger CNC con Piano di Lavoro Verticale, per la<\/p>\n\t\t<\/div>\n\t\t\n\t\t<a class=\"elementor-post__read-more\" href=\"https:\/\/muratorimachines.com\/it\/isa-2026\/\" aria-label=\"Read more about Muratori Machines a ISA Expo 2026: Automazione CNC Verticale per il Sign Making\" tabindex=\"-1\" >\n\t\t\tLeggi di pi\u00f9 \u00bb\t\t<\/a>\n\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/article>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Qual \u00e8 il modo pi\u00f9 efficace per lavorare e rendere bello il bordo dei pannelli? I pannelli compositi per facciate architettoniche, per il settore dei trasporti, cos\u00ec come quelli per l&#8217;industria e il Visual Communication, devono rispondere a precisi requisiti tecnici, garantire ottime performance e resistenza agli agenti atmosferici. Ma anche l&#8217;aspetto estetico riveste un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":11217,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[125,128,243,316,317],"class_list":["post-11076","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologie","tag-sistemi-brevettati","tag-pannelli-compositi","tag-lavorazione-bordo","tag-fresatura-bordo","tag-piegatura-bordo"],"acf":[],"_links":{"self":[{"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/posts\/11076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/comments?post=11076"}],"version-history":[{"count":4,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/posts\/11076\/revisions"}],"predecessor-version":[{"id":21506,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/posts\/11076\/revisions\/21506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/media\/11217"}],"wp:attachment":[{"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/media?parent=11076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/categories?post=11076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/muratorimachines.com\/it\/wp-json\/wp\/v2\/tags?post=11076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}